{"id":6268,"date":"2025-05-28T14:45:36","date_gmt":"2025-05-28T14:45:36","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/"},"modified":"2025-05-28T14:45:36","modified_gmt":"2025-05-28T14:45:36","slug":"simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/","title":{"rendered":"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno"},"content":{"rendered":"\n<p>&nbsp;<\/p>\n\n<p><meta charset=\"utf-8\" \/><\/p>\n\n<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa Refeno\" height=\"602\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_NAVIO CISNE branco marinha do br.jpg\" width=\"900\" \/>\n<figcaption>Foto: Divulga&ccedil;&atilde;o\/Marinha do Brasil<\/figcaption>\n<\/figure>\n<\/div>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">O navio-veleiro Cisne Branco, um dos principais s&iacute;mbolos da Marinha do Brasil, est&aacute; confirmado na 36&ordf; edi&ccedil;&atilde;o da Regata Internacional Recife-Fernando de Noronha (Refeno), prevista para o dia 27 de setembro, no Marco Zero, cora&ccedil;&atilde;o do Recife. A embarca&ccedil;&atilde;o &eacute; conhecida por suas miss&otilde;es diplom&aacute;ticas e por representar o pa&iacute;s em eventos n&aacute;uticos pelo mundo.<\/span><\/span><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Criada em 1986 com apenas 22 participantes, a Refeno se transformou ao longo das d&eacute;cadas em uma das mais prestigiadas regatas do Atl&acirc;ntico Sul, reunindo velejadores de diferentes nacionalidades. Com 300 milhas n&aacute;uticas de percurso &mdash; cerca de 560 km &mdash;, a travessia leva os participantes das &aacute;guas pernambucanas at&eacute; Fernando de Noronha, em meio a paisagens de tirar o f&ocirc;lego, c&eacute;u aberto e vento constante, ideais para a navega&ccedil;&atilde;o.<\/span><\/span><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Constru&iacute;do na Holanda e lan&ccedil;ado ao mar em 1999, o navio foi incorporado &agrave; Marinha do Brasil em 2000, ap&oacute;s cruzar o Atl&acirc;ntico na hist&oacute;rica &ldquo;Rota do Descobrimento&rdquo;, em homenagem aos 500 anos do pa&iacute;s.<\/span><\/span><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">A Refeno &eacute; conhecida por sua diversidade de embarca&ccedil;&otilde;es. Participam barcos das classes ORC, RGS, VPRS, MOCRA, al&eacute;m de multicascos como catamar&atilde;s e trimar&atilde;s, e tamb&eacute;m embarca&ccedil;&otilde;es de alum&iacute;nio, a&ccedil;o, madeira, entre outras. H&aacute; at&eacute; uma categoria destinada aos que preferem navegar sem pressa, aproveitando a travessia como um passeio tur&iacute;stico.<\/span><\/span><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">O recorde geral da prova pertence ao veleiro baiano Adrenalina Pura, que completou o percurso em 14h34min54s, em 2007. Entre os monocascos, o mais veloz foi o Camiranga, do Rio Grande do Sul, que finalizou a rota em 19h03min18s, em 2017.<\/span><\/span><\/p>\n\n<ul>\n\t<li style=\"text-align: justify;\"><a href=\"https:\/\/chat.whatsapp.com\/JmQ0ETtAV4EF3DCBRXrmWk\"><strong><span style=\"color:#000080;\"><span style=\"font-size:16px;\">Clique aqui e fa&ccedil;a parte da comunidade da Compre N&aacute;utica no WhatsApp<\/span><\/span><\/strong><\/a><br \/>\n\t&nbsp;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Foto: Divulga&ccedil;&atilde;o\/Marinha do Brasil O navio-veleiro Cisne Branco, um dos principais s&iacute;mbolos da Marinha do Brasil, est&aacute; confirmado na 36&ordf; edi&ccedil;&atilde;o da Regata Internacional Recife-Fernando de Noronha (Refeno), prevista para o dia 27 de setembro, no Marco Zero, cora&ccedil;&atilde;o do Recife. A embarca&ccedil;&atilde;o &eacute; conhecida por suas miss&otilde;es diplom&aacute;ticas e por representar o pa&iacute;s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6269,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4129],"tags":[],"class_list":["post-6268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Foto: Divulga&ccedil;&atilde;o\/Marinha do Brasil O navio-veleiro Cisne Branco, um dos principais s&iacute;mbolos da Marinha do Brasil, est&aacute; confirmado na 36&ordf; edi&ccedil;&atilde;o da Regata Internacional Recife-Fernando de Noronha (Refeno), prevista para o dia 27 de setembro, no Marco Zero, cora&ccedil;&atilde;o do Recife. A embarca&ccedil;&atilde;o &eacute; conhecida por suas miss&otilde;es diplom&aacute;ticas e por representar o pa&iacute;s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T14:45:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_44276.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno\",\"datePublished\":\"2025-05-28T14:45:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/\"},\"wordCount\":359,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_44276.webp\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/\",\"name\":\"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_44276.webp\",\"datePublished\":\"2025-05-28T14:45:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_44276.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_44276.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/","og_locale":"pt_BR","og_type":"article","og_title":"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"&nbsp; Foto: Divulga&ccedil;&atilde;o\/Marinha do Brasil O navio-veleiro Cisne Branco, um dos principais s&iacute;mbolos da Marinha do Brasil, est&aacute; confirmado na 36&ordf; edi&ccedil;&atilde;o da Regata Internacional Recife-Fernando de Noronha (Refeno), prevista para o dia 27 de setembro, no Marco Zero, cora&ccedil;&atilde;o do Recife. A embarca&ccedil;&atilde;o &eacute; conhecida por suas miss&otilde;es diplom&aacute;ticas e por representar o pa&iacute;s [&hellip;]","og_url":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2025-05-28T14:45:36+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_44276.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno","datePublished":"2025-05-28T14:45:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/"},"wordCount":359,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_44276.webp","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/","url":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/","name":"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_44276.webp","datePublished":"2025-05-28T14:45:36+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_44276.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_44276.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/simbolo-da-marinha-do-brasil-o-navio-veleiro-cisne-branco-participara-da-36a-edicao-da-refeno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"S\u00edmbolo da Marinha do Brasil, o navio-veleiro Cisne Branco participar\u00e1 da 36\u00aa edi\u00e7\u00e3o da Refeno"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/6268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=6268"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/6268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/6269"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=6268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=6268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=6268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}