{"id":6052,"date":"2025-02-14T13:33:10","date_gmt":"2025-02-14T13:33:10","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/"},"modified":"2025-02-14T13:33:10","modified_gmt":"2025-02-14T13:33:10","slug":"2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/","title":{"rendered":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM"},"content":{"rendered":"\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"594\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM palco.png\" width=\"945\" \/><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">O 2&ordm; F&oacute;rum de Seguran&ccedil;a do Navegador Amador (FSNA) aconteceu no &uacute;ltimo s&aacute;bado, dia 8 de fevereiro, no Centro Tecnol&oacute;gico da Marinha em S&atilde;o Paulo (CTMSP). O evento reuniu autoridades e profissionais da &aacute;rea n&aacute;utica, com o objetivo de promover um di&aacute;logo entre a sociedade civil, a comunidade n&aacute;utica e a Marinha do Brasil.<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"598\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador.png\" width=\"915\" \/><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Durante o evento, os participantes discutiram as atualiza&ccedil;&otilde;es das NORMAM 211, que abordam as normas de seguran&ccedil;a para embarca&ccedil;&otilde;es de esporte e recreio, e NORMAM 212, focada no uso comercial de motos aqu&aacute;ticas. As novas regulamenta&ccedil;&otilde;es, que entraram em vigor em 2024, foram detalhadas em palestras e debates com especialistas da Diretoria de Portos e Costas (DPC) da Marinha.<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"589\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Almirante Trov\u00e3o.png\" width=\"906\" \/><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">O Vice-Almirante Marco Ant&ocirc;nio Trov&atilde;o, comandante do Oitavo Distrito Naval, iniciou o evento destacando os <a href=\"https:\/\/www.instagram.com\/p\/DF0PVTdxc6p\/\">principais<\/a> problemas enfrentados pelos navegadores. &quot;N&oacute;s vemos muito a falta de uso do colete e o excesso de velocidade. Ent&atilde;o, &eacute; uma neglig&ecirc;ncia e tamb&eacute;m uma imprud&ecirc;ncia, n&atilde;o uma imper&iacute;cia&quot;, afirmou. Ele tamb&eacute;m mencionou o aplicativo NAVSEG, uma ferramenta essencial para os navegadores: &quot;Nem sempre &eacute; uma imprud&ecirc;ncia ou neglig&ecirc;ncia, &agrave;s vezes temos um problema na embarca&ccedil;&atilde;o e &eacute; necess&aacute;rio que a Marinha seja acionada para o apoio necess&aacute;rio.&quot;<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"596\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Mario Simonsen.png\" width=\"909\" \/><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Al&eacute;m das palestras, o f&oacute;rum proporcionou um espa&ccedil;o para a intera&ccedil;&atilde;o entre os participantes e a Marinha, permitindo que d&uacute;vidas e sugest&otilde;es fossem discutidas. M&aacute;rio Simonsen, presidente da Sociedade Amigos da Marinha de S&atilde;o Paulo (SOAMAR-SP), falou sobre o papel do f&oacute;rum em aproximar a Marinha da comunidade n&aacute;utica: &quot;O principal papel da SOAMAR &eacute; fazer um link entre a Marinha e a sociedade civil. N&oacute;s somos como um bra&ccedil;o civil da Marinha, e essas mudan&ccedil;as nas NORMAM levaram &agrave; cria&ccedil;&atilde;o do primeiro f&oacute;rum em 2023. Agora, com o surgimento de novas d&uacute;vidas, fizemos a segunda edi&ccedil;&atilde;o.&quot;<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"562\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM publico.png\" width=\"892\" \/><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Simonsen tamb&eacute;m destacou como o evento ajuda a quebrar a percep&ccedil;&atilde;o de distanciamento do p&uacute;blico com a Marinha: &quot;O p&uacute;blico considera a Marinha algo distante, e quando fazemos o f&oacute;rum, eles debatem diretamente, a Marinha responde e, nesses momentos, a contribui&ccedil;&atilde;o para a seguran&ccedil;a no mar &eacute; essencial.&quot;<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"600\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Marcello de Souza.png\" width=\"916\" \/><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Por fim, os organizadores enfatizaram a import&acirc;ncia de iniciativas como o FSNA para promover a seguran&ccedil;a no meio n&aacute;utico. Marcello de Souza, organizador do evento, resumiu o papel do f&oacute;rum: &quot;O f&oacute;rum &eacute; um espa&ccedil;o para que todos os envolvidos no meio n&aacute;utico possam trazer suas sugest&otilde;es e problemas, para que, junto com a Marinha, possamos fazer normas mais eficientes.&quot;<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"594\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM.png\" width=\"914\" \/><\/p>\n\n<p style=\"text-align: justify;\"><strong><span style=\"color:#000000;\"><span style=\"font-size:16px;\">Sobre o Evento<\/span><\/span><\/strong><\/p>\n\n<p style=\"text-align: justify;\"><span style=\"color:#000000;\"><span style=\"font-size:16px;\">O 2&ordm; F&oacute;rum de Seguran&ccedil;a do Navegador Amador &eacute; realizado anualmente em parceria com a Marinha do Brasil, a DPC e a SOAMAR-SP. O evento n&atilde;o s&oacute; discute quest&otilde;es t&eacute;cnicas e de seguran&ccedil;a, mas tamb&eacute;m visa criar uma rede de apoio entre navegadores amadores e autoridades, garantindo o cumprimento das normas n&aacute;uticas e a seguran&ccedil;a no mar.<\/span><\/span><\/p>\n\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\" height=\"582\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador_.png\" width=\"951\" \/><\/p>\n\n<p style=\"text-align: justify;\"><br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM.<\/p>\n","protected":false},"author":2,"featured_media":6053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4129],"tags":[5691,4883],"class_list":["post-6052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-2o-forum-de-seguranca-do-navegador-amador","tag-marinha-do-brasil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T13:33:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_41883.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\",\"datePublished\":\"2025-02-14T13:33:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/\"},\"wordCount\":632,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_41883.webp\",\"keywords\":[\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador\",\"Marinha do Brasil\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/\",\"name\":\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_41883.webp\",\"datePublished\":\"2025-02-14T13:33:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_41883.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_41883.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/","og_locale":"pt_BR","og_type":"article","og_title":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM.","og_url":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2025-02-14T13:33:10+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_41883.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM","datePublished":"2025-02-14T13:33:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/"},"wordCount":632,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_41883.webp","keywords":["2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador","Marinha do Brasil"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/","url":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/","name":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_41883.webp","datePublished":"2025-02-14T13:33:10+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_41883.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_41883.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/2o-forum-de-seguranca-do-navegador-amador-debate-atualizacoes-nas-normam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"2\u00ba F\u00f3rum de Seguran\u00e7a do Navegador Amador debate atualiza\u00e7\u00f5es nas NORMAM"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/6052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=6052"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/6052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/6053"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=6052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=6052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=6052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}