{"id":4995,"date":"2022-11-21T16:47:16","date_gmt":"2022-11-21T16:47:16","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/"},"modified":"2022-11-21T16:47:16","modified_gmt":"2022-11-21T16:47:16","slug":"kapazi-nautica-garante-descontos-de-ate-33-na-black-friday","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/","title":{"rendered":"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday"},"content":{"rendered":"\n<p class=\"CxSpFirst\" style=\"margin-right:0cm; text-align:justify\"><span style=\"line-height:normal\">Com expectativa de crescer 10% em rela&ccedil;&atilde;o ao ano passado, o mercado n&aacute;utico no Brasil j&aacute; est&aacute; em ritmo de fim de ano. O per&iacute;odo costuma ser bastante produtivo para o setor, que hoje tem registradas quase 1 milh&atilde;o de embarca&ccedil;&otilde;es no pa&iacute;s. Al&eacute;m da venda de barcos, outro segmento que cresce nos &uacute;ltimos meses do ano &eacute; o de acess&oacute;rios.<\/span><\/p>\n\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"500\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_POST 2.2.png\" width=\"500\" \/><\/p>\n\n<p class=\"CxSpMiddle\" style=\"margin-right:0cm; text-align:justify\"><span style=\"line-height:normal\">H&aacute; mais de 40 anos no mercado de tapetes e capachos, a Kapazi atua tamb&eacute;m na linha n&aacute;utica com revestimento para barcos. A empresa estima um aumento de 30% das vendas para este final de ano. Segundo o gestor comercial, Fernando Soares, &ldquo;nesse per&iacute;odo do ano o mercado &eacute; aquecido devido &agrave;s f&eacute;rias. Todos querem navegar com o barco renovado. Nossa expectativa acompanha esse movimento e, por isso, nos preparamos para atender melhor e mais r&aacute;pido&rdquo;, comenta.<\/span><\/p>\n\n<p class=\"CxSpMiddle\" style=\"margin-right:0cm; text-align:justify\"><span style=\"line-height:normal\">Para incentivar ainda mais as compras nesta &eacute;poca do ano, a Kapazi N&aacute;utica vai apostar na Black Friday para lan&ccedil;ar promo&ccedil;&otilde;es. &ldquo;Estamos com duas grandes a&ccedil;&otilde;es para a Black Friday. Uma delas &eacute; frete gr&aacute;tis para toda linha de pisos n&aacute;uticos. A outra &eacute; o desconto de at&eacute; 33% na nossa linha de copos t&eacute;rmicos&rdquo;, explica Fernando. Quem tiver interesse em aproveitar as ofertas ter&aacute; do dia 24 a 30 de novembro para realizar as compras direto pelo site <a href=\"https:\/\/www.kapazinautica.com.br\/\">kapazinautica.com.br.<\/a><\/span><\/p>\n\n<p style=\"text-align:justify\"><span style=\"line-height:normal\">Ap&oacute;s um ano de lan&ccedil;amentos de produtos e investimento no segmento online, a Kapazi j&aacute; tem boas previs&otilde;es para 2023. &ldquo;Temos uma expectativa de crescimento em torno de 15%, colhendo os resultados de estrat&eacute;gias de expans&atilde;o que fizemos durante 2022. Confiamos que ser&aacute; um bom ano&rdquo;, finaliza o gestor.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para incentivar ainda mais as compras nesta \u00e9poca do ano, a Kapazi N\u00e1utica vai apostar na Black Friday para lan\u00e7ar promo\u00e7\u00f5es com frete gr\u00e1tis e at\u00e9 33% de desconto. Quem tiver interesse em aproveitar as ofertas ter\u00e1 do dia 24 a 30 de novembro.<\/p>\n","protected":false},"author":2,"featured_media":4996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4129],"tags":[4133,4558,4584,4149,4228],"class_list":["post-4995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-barcos","tag-black-friday","tag-desconto","tag-kapazi-nautica","tag-revestimento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Para incentivar ainda mais as compras nesta \u00e9poca do ano, a Kapazi N\u00e1utica vai apostar na Black Friday para lan\u00e7ar promo\u00e7\u00f5es com frete gr\u00e1tis e at\u00e9 33% de desconto. Quem tiver interesse em aproveitar as ofertas ter\u00e1 do dia 24 a 30 de novembro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T16:47:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_23184.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday\",\"datePublished\":\"2022-11-21T16:47:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_23184.webp\",\"keywords\":[\"BARCOS\",\"Black Friday\",\"desconto\",\"kapazi n\u00e1utica\",\"revestimento\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/\",\"name\":\"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_23184.webp\",\"datePublished\":\"2022-11-21T16:47:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_23184.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_23184.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/","og_locale":"pt_BR","og_type":"article","og_title":"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Para incentivar ainda mais as compras nesta \u00e9poca do ano, a Kapazi N\u00e1utica vai apostar na Black Friday para lan\u00e7ar promo\u00e7\u00f5es com frete gr\u00e1tis e at\u00e9 33% de desconto. Quem tiver interesse em aproveitar as ofertas ter\u00e1 do dia 24 a 30 de novembro.","og_url":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-11-21T16:47:16+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_23184.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday","datePublished":"2022-11-21T16:47:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/"},"wordCount":339,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_23184.webp","keywords":["BARCOS","Black Friday","desconto","kapazi n\u00e1utica","revestimento"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/","url":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/","name":"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_23184.webp","datePublished":"2022-11-21T16:47:16+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_23184.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_23184.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/kapazi-nautica-garante-descontos-de-ate-33-na-black-friday\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Kapazi N\u00e1utica garante descontos de at\u00e9 33% na Black Friday"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4995"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4996"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}