{"id":4972,"date":"2022-11-09T12:25:45","date_gmt":"2022-11-09T12:25:45","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/"},"modified":"2026-02-07T15:00:06","modified_gmt":"2026-02-07T15:00:06","slug":"historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/","title":{"rendered":"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos"},"content":{"rendered":"\n<p style=\"text-align:justify\">Quem &eacute; apaixonado por embarca&ccedil;&otilde;es, tamb&eacute;m mant&eacute;m o vivo o interesse por tudo que as cercam, inclusive na hist&oacute;ria. Recentemente, na Cro&aacute;cia, arque&oacute;logos encontraram um barco romano de madeira datado em mais de 2 mil anos. O detalhe mais curioso foi a profundidade em que o barco estava: apenas dois metros.<\/p>\n\n<p style=\"text-align:justify\">As informa&ccedil;&otilde;es sobre a descoberta foram divulgadas no in&iacute;cio do m&ecirc;s pelo Centro Internacional de Arqueologia Subaqu&aacute;tica em Zadar. O barco possui tr&ecirc;s metros de largura aproximadamente e nove metros de comprimento, segundo a equipe respons&aacute;vel pela escava&ccedil;&atilde;o. A embarca&ccedil;&atilde;o estava coberta por areia e teve parte da estrutura externa destru&iacute;da ao longo dos anos.<\/p>\n\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"328\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_csm_barco-romano-descoberto-mar-mundo_e005491238.jpg\" width=\"500\" \/><\/p>\n\n<p>Foto: Reprodu&ccedil;&atilde;o I CUA Zada<\/p>\n\n<p>&nbsp;<\/p>\n\n<p>O barco foi encontrado na proximidade da &aacute;rea portu&aacute;ria de Barbir. Segundo dados hist&oacute;ricos, os romanos realizaram constru&ccedil;&otilde;es no porto entre o s&eacute;culo 1 d.C. e s&eacute;culo 4 d.C. Amostras do barco foram enviadas para serem analisadas na Fran&ccedil;a e sua &aacute;rea ser&aacute; protegida para mais escava&ccedil;&otilde;es e pesquisas sobre a hist&oacute;ria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem \u00e9 apaixonado por embarca\u00e7\u00f5es, tamb\u00e9m mant\u00e9m o vivo o interesse por tudo que as cercam, inclusive na hist\u00f3ria. Recentemente, na Cro\u00e1cia, arque\u00f3logos encontraram um barco romano de madeira datado em mais de 2 mil anos. Saiba mais!<\/p>\n","protected":false},"author":2,"featured_media":4973,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4276,4563,4189,4303],"class_list":["post-4972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-barco","tag-croacia","tag-embarcacao","tag-embarcacoes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Quem \u00e9 apaixonado por embarca\u00e7\u00f5es, tamb\u00e9m mant\u00e9m o vivo o interesse por tudo que as cercam, inclusive na hist\u00f3ria. Recentemente, na Cro\u00e1cia, arque\u00f3logos encontraram um barco romano de madeira datado em mais de 2 mil anos. Saiba mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T12:25:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T15:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_22864.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos\",\"datePublished\":\"2022-11-09T12:25:45+00:00\",\"dateModified\":\"2026-02-07T15:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_22864.webp\",\"keywords\":[\"barco\",\"Cro\u00e1cia\",\"Embarca\u00e7\u00e3o\",\"embarca\u00e7\u00f5es\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/\",\"name\":\"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_22864.webp\",\"datePublished\":\"2022-11-09T12:25:45+00:00\",\"dateModified\":\"2026-02-07T15:00:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_22864.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_22864.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Quem \u00e9 apaixonado por embarca\u00e7\u00f5es, tamb\u00e9m mant\u00e9m o vivo o interesse por tudo que as cercam, inclusive na hist\u00f3ria. Recentemente, na Cro\u00e1cia, arque\u00f3logos encontraram um barco romano de madeira datado em mais de 2 mil anos. Saiba mais!","og_url":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-11-09T12:25:45+00:00","article_modified_time":"2026-02-07T15:00:06+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_22864.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos","datePublished":"2022-11-09T12:25:45+00:00","dateModified":"2026-02-07T15:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/"},"wordCount":235,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_22864.webp","keywords":["barco","Cro\u00e1cia","Embarca\u00e7\u00e3o","embarca\u00e7\u00f5es"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/","url":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/","name":"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_22864.webp","datePublished":"2022-11-09T12:25:45+00:00","dateModified":"2026-02-07T15:00:06+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_22864.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_22864.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/historia-barco-romano-encontrado-na-croacia-tem-mais-de-dois-mil-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"HIST\u00d3RIA: barco romano encontrado na Cro\u00e1cia tem mais de dois mil anos"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4972"}],"version-history":[{"count":1,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4972\/revisions"}],"predecessor-version":[{"id":4974,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4972\/revisions\/4974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4973"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}