{"id":4898,"date":"2022-09-12T14:45:20","date_gmt":"2022-09-12T14:45:20","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/"},"modified":"2026-02-07T14:59:24","modified_gmt":"2026-02-07T14:59:24","slug":"navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/","title":{"rendered":"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo."},"content":{"rendered":"\n<p style=\"text-align:justify\">Um navio inacabado em um estaleiro da Alemanha deve virar sucata e n&atilde;o ter&aacute; sua constru&ccedil;&atilde;o finalizada. O navio que &eacute; um dos maiores cruzeiros do mundo ter&aacute; um novo destino porque a dona da embarca&ccedil;&atilde;o de luxo declarou fal&ecirc;ncia no in&iacute;cio do ano e seus administradores n&atilde;o conseguem encontrar um novo propriet&aacute;rio para o navio de luxo. O valor dele &eacute; avaliado em &pound; 1,2 bilh&atilde;o (equivalente a R$ 7,2 bilh&otilde;es).<\/p>\n\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"266\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Foto-Divulga\u00e7\u00e3o.png\" width=\"500\" \/><\/p>\n\n<p style=\"text-align:justify\">Foto-Divulga&ccedil;&atilde;o<\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p style=\"text-align:justify\">O navio pode transportar at&eacute; 9 mil passageiros e possui 349 metros de comprimento. Ele conta com 20 decks, possui um cinema de luxo e at&eacute; um parque aqu&aacute;tico. O objetivo do estaleiro &eacute; vender partes da embarca&ccedil;&atilde;o. O casco inferior do navio &ndash; o Global Dream ll, tamb&eacute;m deve ser descartado a pre&ccedil;o de sucata.<\/p>\n\n<p style=\"text-align:justify\">A MV Werften, empresa que declarou fal&ecirc;ncia, tamb&eacute;m procurou investidores para a constru&ccedil;&atilde;o ser finalizada e evitar que fosse para a sucata, por&eacute;m, ningu&eacute;m foi encontrado. Caso ningu&eacute;m se manifeste nas pr&oacute;ximas semanas, um processo de licita&ccedil;&atilde;o ser&aacute; iniciado para corretores de navios enviarem suas ofertas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma das maiores embarca\u00e7\u00f5es de cruzeiro do mundo est\u00e1 parado em um estaleiro na Alemanha. O navio que ainda est\u00e1 inacabado dever\u00e1 ser desmantelado antes mesmo de fazer sua primeira viagem. Confira!<\/p>\n","protected":false},"author":2,"featured_media":4899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4499,4395,4471,4500],"class_list":["post-4898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-falencia","tag-luxo","tag-navio","tag-sucata"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo. - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo. - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Uma das maiores embarca\u00e7\u00f5es de cruzeiro do mundo est\u00e1 parado em um estaleiro na Alemanha. O navio que ainda est\u00e1 inacabado dever\u00e1 ser desmantelado antes mesmo de fazer sua primeira viagem. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-12T14:45:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T14:59:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_21875.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo.\",\"datePublished\":\"2022-09-12T14:45:20+00:00\",\"dateModified\":\"2026-02-07T14:59:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_21875.webp\",\"keywords\":[\"Fal\u00eancia\",\"Luxo\",\"navio\",\"Sucata\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/\",\"name\":\"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo. - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_21875.webp\",\"datePublished\":\"2022-09-12T14:45:20+00:00\",\"dateModified\":\"2026-02-07T14:59:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_21875.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_21875.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo. - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/","og_locale":"pt_BR","og_type":"article","og_title":"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo. - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Uma das maiores embarca\u00e7\u00f5es de cruzeiro do mundo est\u00e1 parado em um estaleiro na Alemanha. O navio que ainda est\u00e1 inacabado dever\u00e1 ser desmantelado antes mesmo de fazer sua primeira viagem. Confira!","og_url":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-09-12T14:45:20+00:00","article_modified_time":"2026-02-07T14:59:24+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_21875.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo.","datePublished":"2022-09-12T14:45:20+00:00","dateModified":"2026-02-07T14:59:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/"},"wordCount":239,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_21875.webp","keywords":["Fal\u00eancia","Luxo","navio","Sucata"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/","url":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/","name":"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo. - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_21875.webp","datePublished":"2022-09-12T14:45:20+00:00","dateModified":"2026-02-07T14:59:24+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_21875.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_21875.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/navio-de-luxo-de-r-7-bilhoes-pode-virar-sucata-descubra-o-motivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Navio de luxo de R$ 7 bilh\u00f5es pode virar sucata; descubra o motivo."}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4898"}],"version-history":[{"count":1,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4898\/revisions"}],"predecessor-version":[{"id":4900,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4898\/revisions\/4900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4899"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}