{"id":4816,"date":"2022-08-04T19:33:53","date_gmt":"2022-08-04T19:33:53","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/"},"modified":"2022-08-04T19:33:53","modified_gmt":"2022-08-04T19:33:53","slug":"viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/","title":{"rendered":"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia"},"content":{"rendered":"\n<p style=\"text-align:justify\">Sandro Masseli e Isabela Almeida &ndash; mais conhecida como Bela &ndash; do Viver por Ar e Mar chegaram a Gr&eacute;cia a bordo do veleiro Amaz&ocirc;nia.<\/p>\n\n<p style=\"text-align:justify\">No v&iacute;deo desta semana, eles vivenciaram uma mudan&ccedil;a na previs&atilde;o do tempo que ocasionou em muita chuva e vento. Eles seguiram a caminho de Corfu na Gr&eacute;cia e registraram diversos momentos da cidade grega.<\/p>\n\n<p style=\"text-align:justify\">No v&iacute;deo do Viver por Ar e Mar da semana, voc&ecirc; vai acompanhar golfinhos, tempo agitado, cultura da Gr&eacute;cia, feiras, paisagens lindas e muito mais! &nbsp;<\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p style=\"text-align:justify\">Acompanhe o v&iacute;deo do Viver Por Ar e Mar desta semana!<\/p>\n\n<p style=\"text-align:justify\">A bordo do veleiro Amaz&ocirc;nia e na companhia das cachorras Vick e Chica, o casal do Viver por Ar e Mar compartilha momentos &uacute;nicos ao mar.<\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p><iframe allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/kCbLalmA7jE\" title=\"YouTube video player\" width=\"560\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sandro Masseli e Isabela Almeida do Viver por Ar e Mar chegaram a Gr\u00e9cia. No v\u00eddeo da semana, eles vivenciaram uma mudan\u00e7a na previs\u00e3o do tempo que ocasionou em muita chuva e vento. Eles seguiram a caminho de Corfu e registraram diversos momentos.<\/p>\n","protected":false},"author":2,"featured_media":4817,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4363,4172,4168],"class_list":["post-4816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-grecia","tag-video","tag-viver-por-ar-e-mar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Sandro Masseli e Isabela Almeida do Viver por Ar e Mar chegaram a Gr\u00e9cia. No v\u00eddeo da semana, eles vivenciaram uma mudan\u00e7a na previs\u00e3o do tempo que ocasionou em muita chuva e vento. Eles seguiram a caminho de Corfu e registraram diversos momentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-04T19:33:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20828.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia\",\"datePublished\":\"2022-08-04T19:33:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20828.webp\",\"keywords\":[\"Gr\u00e9cia\",\"v\u00eddeo\",\"viver por ar e mar\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/\",\"name\":\"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20828.webp\",\"datePublished\":\"2022-08-04T19:33:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20828.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20828.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/","og_locale":"pt_BR","og_type":"article","og_title":"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Sandro Masseli e Isabela Almeida do Viver por Ar e Mar chegaram a Gr\u00e9cia. No v\u00eddeo da semana, eles vivenciaram uma mudan\u00e7a na previs\u00e3o do tempo que ocasionou em muita chuva e vento. Eles seguiram a caminho de Corfu e registraram diversos momentos.","og_url":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-08-04T19:33:53+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20828.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia","datePublished":"2022-08-04T19:33:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/"},"wordCount":159,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20828.webp","keywords":["Gr\u00e9cia","v\u00eddeo","viver por ar e mar"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/","url":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/","name":"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20828.webp","datePublished":"2022-08-04T19:33:53+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20828.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20828.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-video-novo-mostra-dias-na-grecia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Viver Por Ar e Mar: v\u00eddeo novo mostra dias na Gr\u00e9cia"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4816"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4817"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}