{"id":4808,"date":"2022-07-31T10:55:41","date_gmt":"2022-07-31T10:55:41","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/viver-por-ar-e-mar-travessia-roma-grecia\/"},"modified":"2022-07-31T10:55:41","modified_gmt":"2022-07-31T10:55:41","slug":"viver-por-ar-e-mar-travessia-roma-grecia","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/","title":{"rendered":"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia"},"content":{"rendered":"\n<p style=\"text-align:justify\">Sandro Masseli e Isabela Almeida &ndash; mais conhecida como Bela &ndash; sa&iacute;ram da It&aacute;lia e chegaram na Gr&eacute;cia.<\/p>\n\n<p style=\"text-align:justify\">No v&iacute;deo desta semana, eles mostraram momentos muito importantes desta travessia da Roma at&eacute; Gr&eacute;cia. O v&iacute;deo come&ccedil;a com Sandro e Bela em Roccella Ionica para seguir a viagem at&eacute; a Gr&eacute;cia. Ao longo dos epis&oacute;dios, &eacute; poss&iacute;vel perceber as mudan&ccedil;as de vegeta&ccedil;&atilde;o bem n&iacute;tidas ao longo de toda a extens&atilde;o da It&aacute;lia.<\/p>\n\n<p style=\"text-align:justify\">No v&iacute;deo do Viver por Ar e Mar da semana, voc&ecirc; vai acompanhar mergulhos, risadas, leveza durante a travessia, momentos especiais com as cachorras Vick e Chica, praias, sa&iacute;das de madrugada, refei&ccedil;&otilde;es especiais, brindes, informa&ccedil;&otilde;es t&eacute;cnicas e muito mais!<\/p>\n\n<p style=\"text-align:justify\">No final, Sandro e Bela chegam at&eacute; o territ&oacute;rio da Gr&eacute;cia, estendem a bandeira do pa&iacute;s no veleiro e iniciam oficialmente novos momentos em um pa&iacute;s diferente.<\/p>\n\n<p style=\"text-align:justify\"><b>Informa&ccedil;&otilde;es do per&iacute;odo at&eacute; a Gr&eacute;cia do Viver por Ar e Mar: <\/b><\/p>\n\n<p style=\"text-align:justify\">14 ancoragens<\/p>\n\n<p style=\"text-align:justify\">17 dias de viagem<\/p>\n\n<p style=\"text-align:justify\">575 milhas navegadas<\/p>\n\n<p style=\"text-align:justify\">115 horas navegando<\/p>\n\n<p style=\"text-align:justify\">280 litros de diesel<\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p style=\"text-align:justify\">Acompanhe o v&iacute;deo do Viver Por Ar e Mar desta semana!<\/p>\n\n<p style=\"text-align:justify\">A bordo do veleiro Amaz&ocirc;nia e na companhia das cachorras Vick e Chica, o casal do Viver por Ar e Mar compartilha momentos &uacute;nicos no mar.<\/p>\n\n<p><iframe allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/tD7VLMF6Y6A\" title=\"YouTube video player\" width=\"560\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sandro Masseli e Isabela Almeida \u2013 mais conhecida como Bela \u2013 sa\u00edram da It\u00e1lia e chegaram na Gr\u00e9cia. No v\u00eddeo desta semana, eles mostraram momentos muito importantes desta travessia Roma at\u00e9 Gr\u00e9cia. Confira!<\/p>\n","protected":false},"author":2,"featured_media":4809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4365,4363,4211,4364,4172,4168],"class_list":["post-4808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-bela","tag-grecia","tag-italia","tag-sandro","tag-video","tag-viver-por-ar-e-mar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Sandro Masseli e Isabela Almeida \u2013 mais conhecida como Bela \u2013 sa\u00edram da It\u00e1lia e chegaram na Gr\u00e9cia. No v\u00eddeo desta semana, eles mostraram momentos muito importantes desta travessia Roma at\u00e9 Gr\u00e9cia. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T10:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20656.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia\",\"datePublished\":\"2022-07-31T10:55:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20656.webp\",\"keywords\":[\"Bela\",\"Gr\u00e9cia\",\"It\u00e1lia\",\"Sandro\",\"v\u00eddeo\",\"viver por ar e mar\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/\",\"name\":\"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20656.webp\",\"datePublished\":\"2022-07-31T10:55:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20656.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_20656.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-travessia-roma-grecia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/","og_locale":"pt_BR","og_type":"article","og_title":"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Sandro Masseli e Isabela Almeida \u2013 mais conhecida como Bela \u2013 sa\u00edram da It\u00e1lia e chegaram na Gr\u00e9cia. No v\u00eddeo desta semana, eles mostraram momentos muito importantes desta travessia Roma at\u00e9 Gr\u00e9cia. Confira!","og_url":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-07-31T10:55:41+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20656.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia","datePublished":"2022-07-31T10:55:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/"},"wordCount":275,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20656.webp","keywords":["Bela","Gr\u00e9cia","It\u00e1lia","Sandro","v\u00eddeo","viver por ar e mar"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/","url":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/","name":"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20656.webp","datePublished":"2022-07-31T10:55:41+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20656.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_20656.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-travessia-roma-grecia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Viver Por Ar e Mar: travessia Roma \u2013 Gr\u00e9cia"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4808"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4809"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}