{"id":4757,"date":"2022-07-06T21:47:13","date_gmt":"2022-07-06T21:47:13","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/casal-nautico-passeio-de-4-dias-com-amigos\/"},"modified":"2022-07-06T21:47:13","modified_gmt":"2022-07-06T21:47:13","slug":"casal-nautico-passeio-de-4-dias-com-amigos","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/","title":{"rendered":"Casal N\u00e1utico: passeio de 4 dias com amigos"},"content":{"rendered":"\n<p style=\"text-align:justify\">O casal Michella Pierri e Walter Kohn do Casal N&aacute;utico realizou um passeio de lancha por 4 dias ao lado de amigos com outras lanchas tamb&eacute;m. No trajeto eles conhecerem lugares incr&iacute;veis e registraram momentos inesquec&iacute;veis como a apari&ccedil;&atilde;o de um pinguim.<\/p>\n\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"467\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Casal N\u00e1utico passeio de 4 dias com amigos _4.jpeg\" width=\"350\" \/><\/p>\n\n<p style=\"text-align:justify\">Entre os momentos especiais est&aacute; um risoto de camar&atilde;o, dias de descanso com &aacute;guas cristalinas e mar calmo, wakeboard e muito mais. Eles passaram na enseada de Porto Belo nas praias de Caixada&ccedil;o, Praia do Pipoca em Porto Belo, Santa Catarina.<\/p>\n\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"\" height=\"622\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Casal N\u00e1utico passeio de 4 dias com amigos _5.jpeg\" width=\"350\" \/><\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"\" height=\"622\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Casal N\u00e1utico passeio de 4 dias com amigos _3.jpeg\" width=\"350\" \/><\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p style=\"text-align:justify\"><em>Acompanhe toda quinta-feira nas redes sociais e no blog da Compre N&aacute;utica o conte&uacute;do feito em parceria com o Casal N&aacute;utico.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O casal Michella Pierri e Walter Kohn do Casal N\u00e1utico realizou um passeio de lancha por 4 dias ao lado de amigos com outras lanchas tamb\u00e9m. Eles conhecerem lugares incr\u00edveis e registraram momentos inesquec\u00edveis como a apari\u00e7\u00e3o de um pinguim.<\/p>\n","protected":false},"author":2,"featured_media":4758,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4352,4317,4190,4376],"class_list":["post-4757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-casal","tag-casal-nautico","tag-lancha","tag-passeio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casal N\u00e1utico: passeio de 4 dias com amigos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casal N\u00e1utico: passeio de 4 dias com amigos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"O casal Michella Pierri e Walter Kohn do Casal N\u00e1utico realizou um passeio de lancha por 4 dias ao lado de amigos com outras lanchas tamb\u00e9m. Eles conhecerem lugares incr\u00edveis e registraram momentos inesquec\u00edveis como a apari\u00e7\u00e3o de um pinguim.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T21:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_19831.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Casal N\u00e1utico: passeio de 4 dias com amigos\",\"datePublished\":\"2022-07-06T21:47:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/\"},\"wordCount\":136,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_19831.webp\",\"keywords\":[\"Casal\",\"Casal N\u00e1utico\",\"Lancha\",\"Passeio\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/\",\"name\":\"Casal N\u00e1utico: passeio de 4 dias com amigos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_19831.webp\",\"datePublished\":\"2022-07-06T21:47:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_19831.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_19831.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/casal-nautico-passeio-de-4-dias-com-amigos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casal N\u00e1utico: passeio de 4 dias com amigos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casal N\u00e1utico: passeio de 4 dias com amigos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/","og_locale":"pt_BR","og_type":"article","og_title":"Casal N\u00e1utico: passeio de 4 dias com amigos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"O casal Michella Pierri e Walter Kohn do Casal N\u00e1utico realizou um passeio de lancha por 4 dias ao lado de amigos com outras lanchas tamb\u00e9m. Eles conhecerem lugares incr\u00edveis e registraram momentos inesquec\u00edveis como a apari\u00e7\u00e3o de um pinguim.","og_url":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-07-06T21:47:13+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_19831.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Casal N\u00e1utico: passeio de 4 dias com amigos","datePublished":"2022-07-06T21:47:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/"},"wordCount":136,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_19831.webp","keywords":["Casal","Casal N\u00e1utico","Lancha","Passeio"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/","url":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/","name":"Casal N\u00e1utico: passeio de 4 dias com amigos - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_19831.webp","datePublished":"2022-07-06T21:47:13+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_19831.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_19831.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/casal-nautico-passeio-de-4-dias-com-amigos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Casal N\u00e1utico: passeio de 4 dias com amigos"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4757"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4758"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}