{"id":4653,"date":"2022-05-06T16:14:18","date_gmt":"2022-05-06T16:14:18","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/"},"modified":"2022-05-06T16:14:18","modified_gmt":"2022-05-06T16:14:18","slug":"iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/","title":{"rendered":"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade"},"content":{"rendered":"\n<p style=\"text-align:justify\">Recentemente o navio de pesquisa e maior iate do mundo (research and expedition vessel &ndash; REV) Ocean divulgou que sua embarca&ccedil;&atilde;o vai obter um submarino para mergulhos que podem chegar at&eacute; 2.300 metros de profundidade com capacidade para levar tr&ecirc;s pessoas. O submarino foi nomeado de Aurelia e foi projetado pela empresa americana Triton Submarines.<\/p>\n\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"600\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade_1.jpg\" width=\"800\" \/><\/p>\n\n<p style=\"text-align:justify\">Foto: Divulga&ccedil;&atilde;o\/REV Ocean&nbsp;<\/p>\n\n<p style=\"text-align:justify\">O submarino &eacute; composto por uma espessa esfera de acr&iacute;lico que permitem a observa&ccedil;&atilde;o de todo o redor do fundo do mar. O ve&iacute;culo possuiu um atraso em seu lan&ccedil;amento que hoje &eacute; previsto para 2026. Atualmente ele inicia a fase de teste de amor junto a REV Ocean para analisar toda a sua seguran&ccedil;a e realizar ajustes finais. Ele tamb&eacute;m &eacute; equipado com sensores cient&iacute;ficos, ferramentas, c&acirc;meras e equipamentos de amostragem o que releva a import&acirc;ncia do ve&iacute;culo em escala cient&iacute;fica para estudos e an&aacute;lises.<\/p>\n\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"\" height=\"534\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade_2.jpg\" width=\"800\" \/><\/p>\n\n<p style=\"text-align:justify\">Foto: Divulga&ccedil;&atilde;o\/REV Ocean<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O navio de pesquisa e maior iate do mundo Ocean divulgou que sua embarca\u00e7\u00e3o vai obter um submarino para mergulhos que podem chegar at\u00e9 2.300 metros de profundidade com capacidade para levar tr\u00eas pessoas.<\/p>\n","protected":false},"author":2,"featured_media":4654,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4242,4136,4208,4241,4220,4212,4243],"class_list":["post-4653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-assuntos-nauticos","tag-compre-nautica","tag-iate","tag-materias","tag-pesquisa","tag-reportagens","tag-submarino"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"O navio de pesquisa e maior iate do mundo Ocean divulgou que sua embarca\u00e7\u00e3o vai obter um submarino para mergulhos que podem chegar at\u00e9 2.300 metros de profundidade com capacidade para levar tr\u00eas pessoas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-06T16:14:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_16446.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade\",\"datePublished\":\"2022-05-06T16:14:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_16446.webp\",\"keywords\":[\"Assuntos n\u00e1uticos\",\"COMPRE NAUTICA\",\"iate\",\"Mat\u00e9rias\",\"pesquisa\",\"Reportagens\",\"Submarino\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/\",\"name\":\"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_16446.webp\",\"datePublished\":\"2022-05-06T16:14:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_16446.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_16446.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"O navio de pesquisa e maior iate do mundo Ocean divulgou que sua embarca\u00e7\u00e3o vai obter um submarino para mergulhos que podem chegar at\u00e9 2.300 metros de profundidade com capacidade para levar tr\u00eas pessoas.","og_url":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-05-06T16:14:18+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_16446.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade","datePublished":"2022-05-06T16:14:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/"},"wordCount":196,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_16446.webp","keywords":["Assuntos n\u00e1uticos","COMPRE NAUTICA","iate","Mat\u00e9rias","pesquisa","Reportagens","Submarino"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/","url":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/","name":"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_16446.webp","datePublished":"2022-05-06T16:14:18+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_16446.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_16446.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/iate-recebe-submarino-de-mergulho-que-chega-a-2-300-metros-de-profundidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Iate recebe submarino de mergulho que chega a 2.300 metros de profundidade"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4653"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4654"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}