{"id":4615,"date":"2022-04-10T11:28:39","date_gmt":"2022-04-10T11:28:39","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/"},"modified":"2022-04-10T11:28:39","modified_gmt":"2022-04-10T11:28:39","slug":"viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/","title":{"rendered":"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia"},"content":{"rendered":"\n<p style=\"text-align:justify\">Com a leveza de sempre, o casal Sandro e Bela a bordo no veleiro Amaz&ocirc;nia compartilham os desafios e recompensas da retomada da viagem pelo mundo. Eles se encontram na It&aacute;lia com o objetivo de seguirem at&eacute; a Gr&eacute;cia. No epis&oacute;dio dessa semana, eles dividem a experi&ecirc;ncia de instalar um freezer de conex&atilde;o r&aacute;pida e os imprevistos que aconteceram durante o processo.<\/p>\n\n<p style=\"text-align:justify\">Conte&uacute;do que vai chamar a sua aten&ccedil;&atilde;o pela autenticidade e a rotina de viver a vida que eles sonharam.<\/p>\n\n<p style=\"text-align:justify\">&nbsp;<\/p>\n\n<p><iframe allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/y395VbwzDak\" title=\"YouTube video player\" width=\"560\"><\/iframe><\/p>\n\n<p>Se interessou pela hist&oacute;ria? <a href=\"https:\/\/comprenautica.com.br\/blog\/revista-digital-nautica-a-arte-de-navegar-marco-2022.html\">Clique aqui<\/a> e acompanhe a mat&eacute;ria completa sobre a hist&oacute;ria do Viver Por Ar e Mar em nossa 1&ordf; edi&ccedil;&atilde;o da revista digital &#39;A Arte de Navegar&#39;. Tamb&eacute;m siga o casal no Instagram @<a href=\"https:\/\/www.instagram.com\/viverporaremar\/\">viverporaremar <\/a>e se inscreva no canal do <a href=\"https:\/\/www.youtube.com\/channel\/UCriGJIVbzYumuyg8m56HJlQ\">Youtube <\/a>Viver por Ar e Mar.<\/p>\n\n<p><em><strong>Reda&ccedil;&atilde;o:<\/strong>&nbsp;Carolina Armelin Piazentin<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo epis\u00f3dio da parceria entre o Viver por Ar e Mar e a Compre N\u00e1utica. Acompanhe todo domingo Sandro e Bela na temporada 2022 das suas viagens no veleiro &#8216;Amaz\u00f4nia&#8217;. No epis\u00f3dio de hoje eles compartilham os desafios di\u00e1rios desta experi\u00eancia.<\/p>\n","protected":false},"author":2,"featured_media":4616,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4171,4136,4170,4173,4169,4167,4172,4168],"class_list":["post-4615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-aventura","tag-compre-nautica","tag-europa","tag-parceria","tag-veleiro","tag-viagem","tag-video","tag-viver-por-ar-e-mar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Segundo epis\u00f3dio da parceria entre o Viver por Ar e Mar e a Compre N\u00e1utica. Acompanhe todo domingo Sandro e Bela na temporada 2022 das suas viagens no veleiro &#039;Amaz\u00f4nia&#039;. No epis\u00f3dio de hoje eles compartilham os desafios di\u00e1rios desta experi\u00eancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-10T11:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_15530.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia\",\"datePublished\":\"2022-04-10T11:28:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/\"},\"wordCount\":185,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_15530.webp\",\"keywords\":[\"aventura\",\"COMPRE NAUTICA\",\"europa\",\"parceria\",\"veleiro\",\"viagem\",\"v\u00eddeo\",\"viver por ar e mar\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/\",\"name\":\"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_15530.webp\",\"datePublished\":\"2022-04-10T11:28:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_15530.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_15530.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/","og_locale":"pt_BR","og_type":"article","og_title":"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Segundo epis\u00f3dio da parceria entre o Viver por Ar e Mar e a Compre N\u00e1utica. Acompanhe todo domingo Sandro e Bela na temporada 2022 das suas viagens no veleiro 'Amaz\u00f4nia'. No epis\u00f3dio de hoje eles compartilham os desafios di\u00e1rios desta experi\u00eancia.","og_url":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-04-10T11:28:39+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_15530.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia","datePublished":"2022-04-10T11:28:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/"},"wordCount":185,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_15530.webp","keywords":["aventura","COMPRE NAUTICA","europa","parceria","veleiro","viagem","v\u00eddeo","viver por ar e mar"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/","url":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/","name":"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_15530.webp","datePublished":"2022-04-10T11:28:39+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_15530.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_15530.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/viver-por-ar-e-mar-2o-episodio-e-marcado-por-desafios-do-dia-a-dia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Viver por Ar e Mar: 2\u00ba Epis\u00f3dio \u00e9 marcado por desafios do dia a dia"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4615"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4616"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}