{"id":4603,"date":"2022-03-07T00:35:51","date_gmt":"2022-03-07T00:35:51","guid":{"rendered":"https:\/\/blog.comprenautica.com.br\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/"},"modified":"2022-03-07T00:35:51","modified_gmt":"2022-03-07T00:35:51","slug":"conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes","status":"publish","type":"post","link":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/","title":{"rendered":"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es"},"content":{"rendered":"\n<p style=\"text-align: justify;\">Conhe&ccedil;a o super iate de&nbsp;Roman Abromovich&nbsp;que custa&nbsp;R$ 7 bilh&otilde;es!&nbsp;<\/p>\n\n<p style=\"text-align: justify;\">Bilion&aacute;rio dono do Chelsea possui&nbsp;iate&nbsp;considerado o mais seguro do planeta.&nbsp;<\/p>\n\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"337\" src=\"blob:https:\/\/comprenautica.com.br\/f3e78283-cf01-4873-9c08-800b426ff203\" width=\"600\" \/><\/p>\n\n<p style=\"text-align: justify;\">Foto: Divulga&ccedil;&atilde;o<\/p>\n\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n\n<p style=\"text-align: justify;\">Em momento&nbsp;de guerra,&nbsp;nomeado de Eclipse, o iate de Roman Abromovich coleciona curiosidades e gera interesse pelas particularidades que possui. Ele&nbsp;tem&nbsp;vidros blindados, dois helipontos, tr&ecirc;s barcos acoplados, mini&nbsp;submarino&nbsp;que submerge at&eacute; 50 metros&nbsp;e uma prote&ccedil;&atilde;o de defesa antim&iacute;sseis. Foram 5 anos de constru&ccedil;&atilde;o com custo de 300 milh&otilde;es de libras na &eacute;poca &ndash; sendo finalizado em 2010. O salto&nbsp;que&nbsp;surpreende &eacute; do valor estimado atual da embarca&ccedil;&atilde;o que alcan&ccedil;a 1,1 bilh&atilde;o de libras.&nbsp;<\/p>\n\n<p style=\"text-align: justify;\">Com valor de manuten&ccedil;&atilde;o, o dono do Chelsea gasta 40 milh&otilde;es de libras anualmente para essa finalidade. O super iate possui uma estrutura completa e comporta at&eacute; 70 h&oacute;spedes. O lugar possui 24 quartos, boate, sal&atilde;o de beleza e spa, sal&atilde;o de jogos, piscinas, &aacute;rea de sauna, churrasqueiras, nove decks, banheiras de hidromassagem e outros espa&ccedil;os luxuosos. Tudo isso em suas 13 mil toneladas e 165,5 metros de comprimento.&nbsp;<\/p>\n\n<p style=\"text-align: justify;\">O Eclipse &eacute; um iate a motor de luxo constru&iacute;do&nbsp;pela Blohm + Voss de Hamburgo. Ele emprega um sistema de estabiliza&ccedil;&atilde;o e em velocidades mais baixas, com base no efeito Magnus.<\/p>\n\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n\n<p style=\"text-align: justify;\">REDA&Ccedil;&Atilde;O: Carolina Piazentin&nbsp;<\/p>\n\n<p style=\"text-align: justify;\"><img decoding=\"async\" alt=\"\" height=\"141\" src=\"\/blog\/\/custom\/domain_1\/image_files\/ckeditor\/sitemgr_5BED2578-29C9-4B59-8587-A121396938E5.png\" width=\"250\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a o super iate de Roman Abromovich que custa R$ 7 bilh\u00f5es!  Em momento de guerra, Bilion\u00e1rio dono do Chelsea possui iate considerado o mais seguro do planeta.  Confira essa mat\u00e9ria!<\/p>\n","protected":false},"author":2,"featured_media":4604,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4144],"tags":[4161,4162,4160,4165,4164,4159,4163],"class_list":["post-4603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-iate-de-7-bilhoes","tag-iate-de-7-bilhoes-e-o-mais-seguro-do-mundo","tag-iate-mais-seguro-do-mundo","tag-iate-preparado-para-guerra","tag-preparado-para-guerra","tag-super-iate","tag-super-iate-de-dono-do-chelsea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a o super iate de Roman Abromovich que custa R$ 7 bilh\u00f5es! Em momento de guerra, Bilion\u00e1rio dono do Chelsea possui iate considerado o mais seguro do planeta. Confira essa mat\u00e9ria!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-07T00:35:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_13106.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Carolina Piazentin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina Piazentin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/\"},\"author\":{\"name\":\"Carolina Piazentin\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\"},\"headline\":\"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es\",\"datePublished\":\"2022-03-07T00:35:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/\"},\"wordCount\":294,\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_13106.webp\",\"keywords\":[\"iate de 7 bilh\u00f5es\",\"iate de 7 bilh\u00f5es \u00e9 o mais seguro do mundo\",\"Iate mais seguro do mundo\",\"iate preparado para guerra\",\"Preparado para guerra\",\"Super iate\",\"Super iate de dono do chelsea\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/\",\"name\":\"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_13106.webp\",\"datePublished\":\"2022-03-07T00:35:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_13106.webp\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sitemgr_photo_13106.webp\",\"width\":560,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"description\":\"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#organization\",\"name\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"contentUrl\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/V.1.png\",\"width\":1085,\"height\":177,\"caption\":\"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica\"},\"image\":{\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4738c9b8bd76b4087e156c7ed165bba0\",\"name\":\"Carolina Piazentin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g\",\"caption\":\"Carolina Piazentin\"},\"url\":\"https:\\\/\\\/comprenautica.com.br\\\/blog\\\/author\\\/caroline-piazentin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","og_description":"Conhe\u00e7a o super iate de Roman Abromovich que custa R$ 7 bilh\u00f5es! Em momento de guerra, Bilion\u00e1rio dono do Chelsea possui iate considerado o mais seguro do planeta. Confira essa mat\u00e9ria!","og_url":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/","og_site_name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","article_published_time":"2022-03-07T00:35:51+00:00","og_image":[{"width":560,"height":420,"url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_13106.webp","type":"image\/webp"}],"author":"Carolina Piazentin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carolina Piazentin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#article","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/"},"author":{"name":"Carolina Piazentin","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0"},"headline":"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es","datePublished":"2022-03-07T00:35:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/"},"wordCount":294,"publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_13106.webp","keywords":["iate de 7 bilh\u00f5es","iate de 7 bilh\u00f5es \u00e9 o mais seguro do mundo","Iate mais seguro do mundo","iate preparado para guerra","Preparado para guerra","Super iate","Super iate de dono do chelsea"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/","url":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/","name":"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es - Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","isPartOf":{"@id":"https:\/\/comprenautica.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#primaryimage"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_13106.webp","datePublished":"2022-03-07T00:35:51+00:00","breadcrumb":{"@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#primaryimage","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_13106.webp","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2026\/02\/sitemgr_photo_13106.webp","width":560,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comprenautica.com.br\/blog\/conheca-o-super-iate-do-dono-de-chelsea-o-mais-seguro-do-mundo-avaliado-em-mais-de-r7-bilhoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/comprenautica.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a o super iate do dono de Chelsea, o mais seguro do mundo avaliado em mais de R$7 Bilh\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/comprenautica.com.br\/blog\/#website","url":"https:\/\/comprenautica.com.br\/blog\/","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","description":"Fique por dentro do melhor do mundo n\u00e1utico com o BLOG Compre N\u00e1utica. S\u00e3o noticias, informa\u00e7\u00f5es do mercado e da marinha, dicas, ensinamentos, historias reais e muitaaaa n\u00e1utica. Vem conferir!","publisher":{"@id":"https:\/\/comprenautica.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comprenautica.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/comprenautica.com.br\/blog\/#organization","name":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica","url":"https:\/\/comprenautica.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","contentUrl":"https:\/\/comprenautica.com.br\/blog\/wp-content\/uploads\/2025\/12\/V.1.png","width":1085,"height":177,"caption":"Fique por dentro das principais not\u00edcias n\u00e1uticas | Compre N\u00e1utica"},"image":{"@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/comprenautica.com.br\/blog\/#\/schema\/person\/4738c9b8bd76b4087e156c7ed165bba0","name":"Carolina Piazentin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b447e1d5e2c2ff9eef0304b29cfecf819130250c516b0302d2ef755be72a573d?s=96&d=mm&r=g","caption":"Carolina Piazentin"},"url":"https:\/\/comprenautica.com.br\/blog\/author\/caroline-piazentin\/"}]}},"_links":{"self":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4603"}],"version-history":[{"count":0,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/posts\/4603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media\/4604"}],"wp:attachment":[{"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprenautica.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}